{"id":157,"date":"2025-03-04T17:15:31","date_gmt":"2025-03-04T17:15:31","guid":{"rendered":"https:\/\/demo1.chequechulo.com\/terms-and-conditions\/"},"modified":"2025-05-02T20:05:26","modified_gmt":"2025-05-02T18:05:26","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/demo1.chequechulo.com\/fr\/conditions-generales\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales d'utilisation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"157\" class=\"elementor elementor-157\">\n\t\t\t\t<div class=\"elementor-element elementor-element-zwh4n4o9 twbb_section e-flex e-con-boxed e-con e-parent\" data-id=\"zwh4n4o9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-nueq9zjq elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"nueq9zjq\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conditions g\u00e9n\u00e9rales d'utilisation<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8s122m95 twbb_section e-flex e-con-boxed e-con e-parent\" data-id=\"8s122m95\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-yk0xi23d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"yk0xi23d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Conditions d'utilisation d'Imprepapelx S.L.U.<\/strong><\/h3><p>Estos t\u00e9rminos y condiciones rigen el uso del sitio web y la tienda online de <strong>Imprepapelx S.L.U.<\/strong> Al acceder o utilizar este sitio web, usted acepta estar sujeto a estos t\u00e9rminos y condiciones.<\/p><h4>1. acceptation des conditions<\/h4><p>En utilisant ce site web, vous reconnaissez avoir lu, compris et accept\u00e9 d'\u00eatre li\u00e9 par ces termes et conditions. Si vous n'acceptez pas ces conditions, il vous est interdit d'utiliser ce site web.<\/p><h4>2. Utilisation du site web<\/h4><p>Vous acceptez de n'utiliser ce site web qu'\u00e0 des fins l\u00e9gales. Il vous est interdit de vous livrer \u00e0 toute activit\u00e9 susceptible d'endommager, de d\u00e9sactiver, de surcharger ou d'alt\u00e9rer le site web ou ses fonctionnalit\u00e9s.<\/p><h4>3. La propri\u00e9t\u00e9 intellectuelle<\/h4><p>Tout le contenu de ce site web, y compris, mais sans s'y limiter, le texte, les graphiques, les logos et les images, est la propri\u00e9t\u00e9 d'Imprepapelx S.L.U. ou de ses conc\u00e9dants de licence. Vous disposez d'une licence limit\u00e9e, non exclusive et non transf\u00e9rable pour acc\u00e9der au site web et l'utiliser \u00e0 des fins personnelles et non commerciales.<\/p><h4>4. Limitation de la responsabilit\u00e9<\/h4><p><strong>Imprepapelx S.L.U.<\/strong> no ser\u00e1 responsable de ning\u00fan da\u00f1o que surja de su uso de este sitio web, incluidos, entre otros, da\u00f1os directos, indirectos, incidentales, consecuentes o punitivos.<\/p><p>5. Droit applicable<\/p><p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales sont r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment aux lois espagnoles.<\/p><h4>6. Modifications des conditions<\/h4><p><strong>Imprepapelx S.L.U.<\/strong> se reserva el derecho de modificar estos t\u00e9rminos y condiciones en cualquier momento. Cualquier cambio entrar\u00e1 en vigor inmediatamente despu\u00e9s de su publicaci\u00f3n en este sitio web.<\/p><h4>7. Nous contacter \u00e0 l'adresse suivante<\/h4><p>Si vous avez des questions ou des pr\u00e9occupations concernant les pr\u00e9sentes conditions g\u00e9n\u00e9rales, veuillez nous contacter \u00e0 l'adresse info@imprepapelx.com.<\/p><p>\u00a0<\/p><h3 data-start=\"230\" data-end=\"267\"><strong data-start=\"230\" data-end=\"267\">Pol\u00edtica de Env\u00edos y Devoluciones<\/strong><\/h3><p class=\"\" data-start=\"269\" data-end=\"621\"><strong data-start=\"269\" data-end=\"301\">Titular de la tienda online:<\/strong><br data-start=\"301\" data-end=\"304\" \/><strong data-start=\"304\" data-end=\"325\">IMPREPAPELX, S.L.<\/strong><br data-start=\"325\" data-end=\"328\" \/>CIF: B54631536<br data-start=\"342\" data-end=\"345\" \/>Domicilio social: Partida de Alzabares Bajo, 130, 03290 Elche (Alicante), Espa\u00f1a<br data-start=\"425\" data-end=\"428\" \/>Tel\u00e9fono de contacto: 966 613 220<br data-start=\"461\" data-end=\"464\" \/>Correo electr\u00f3nico: <a class=\"cursor-pointer\" rel=\"noopener\" data-start=\"484\" data-end=\"504\">info@imprepapelx.com<\/a><br data-start=\"504\" data-end=\"507\" \/>Actividad principal: Comercio al por mayor y menor de material de oficina, papeler\u00eda, embalaje y art\u00edculos afines.<\/p><hr class=\"\" data-start=\"623\" data-end=\"626\" \/><h3 class=\"\" data-start=\"628\" data-end=\"638\">Env\u00edos<\/h3><p class=\"\" data-start=\"640\" data-end=\"794\">En Imprepapelx.com nos comprometemos a gestionar y preparar tu pedido con la mayor rapidez posible. No obstante, ten en cuenta las siguientes condiciones:<\/p><ul data-start=\"796\" data-end=\"1218\"><li class=\"\" data-start=\"796\" data-end=\"932\"><p class=\"\" data-start=\"798\" data-end=\"932\"><strong data-start=\"798\" data-end=\"831\">Plazo de preparaci\u00f3n y env\u00edo:<\/strong> Los pedidos se procesan en un plazo m\u00e1ximo de <strong data-start=\"878\" data-end=\"898\">72 horas h\u00e1biles<\/strong> desde la confirmaci\u00f3n del pedido.<\/p><\/li><li class=\"\" data-start=\"933\" data-end=\"1218\"><p class=\"\" data-start=\"935\" data-end=\"1218\"><strong data-start=\"935\" data-end=\"967\">Disponibilidad de productos:<\/strong> En caso de que alg\u00fan art\u00edculo no est\u00e9 disponible en el momento de procesar el pedido, nos pondremos en contacto con el cliente para ofrecer una alternativa, acordar una fecha de entrega posterior o gestionar la devoluci\u00f3n del importe correspondiente.<\/p><\/li><\/ul><hr class=\"\" data-start=\"1220\" data-end=\"1223\" \/><h3 class=\"\" data-start=\"1225\" data-end=\"1241\">Devoluciones<\/h3><p class=\"\" data-start=\"1243\" data-end=\"1433\">En Imprepapelx.com deseamos que nuestros clientes queden completamente satisfechos con su compra. Por ello, ofrecemos la posibilidad de realizar devoluciones bajo las siguientes condiciones:<\/p><ul data-start=\"1435\" data-end=\"2222\"><li class=\"\" data-start=\"1435\" data-end=\"1570\"><p class=\"\" data-start=\"1437\" data-end=\"1570\"><strong data-start=\"1437\" data-end=\"1465\">Plazo para devoluciones:<\/strong> El cliente dispone de <strong data-start=\"1488\" data-end=\"1509\">15 d\u00edas naturales<\/strong> desde la recepci\u00f3n del pedido para solicitar una devoluci\u00f3n.<\/p><\/li><li class=\"\" data-start=\"1571\" data-end=\"1841\"><p class=\"\" data-start=\"1573\" data-end=\"1841\"><strong data-start=\"1573\" data-end=\"1602\">Condiciones del art\u00edculo:<\/strong> El producto deber\u00e1 encontrarse <strong data-start=\"1634\" data-end=\"1656\">en perfecto estado<\/strong>, <strong data-start=\"1658\" data-end=\"1670\">sin usar<\/strong> y <strong data-start=\"1673\" data-end=\"1709\">con su embalaje original intacto<\/strong>, salvo en los casos en los que la devoluci\u00f3n se deba a un <strong data-start=\"1768\" data-end=\"1811\">error cometido por parte de Imprepapelx<\/strong> en la preparaci\u00f3n del pedido.<\/p><\/li><li class=\"\" data-start=\"1842\" data-end=\"1988\"><p class=\"\" data-start=\"1844\" data-end=\"1988\"><strong data-start=\"1844\" data-end=\"1869\">Gastos de devoluci\u00f3n:<\/strong> Salvo en caso de error imputable a Imprepapelx, <strong data-start=\"1918\" data-end=\"1987\">los gastos de env\u00edo por devoluci\u00f3n correr\u00e1n a cargo del comprador<\/strong>.<\/p><\/li><li class=\"\" data-start=\"1989\" data-end=\"2222\"><p class=\"\" data-start=\"1991\" data-end=\"2222\"><strong data-start=\"1991\" data-end=\"2015\">Proceso y reembolso:<\/strong> Una vez recibido el art\u00edculo en nuestras instalaciones y tras su revisi\u00f3n, se proceder\u00e1 a la <strong data-start=\"2109\" data-end=\"2137\">sustituci\u00f3n del producto<\/strong> o al <strong data-start=\"2143\" data-end=\"2175\">reembolso del importe pagado<\/strong>, en un plazo de entre <strong data-start=\"2198\" data-end=\"2221\">5 y 10 d\u00edas h\u00e1biles<\/strong>.<\/p><\/li><\/ul><hr class=\"\" data-start=\"2224\" data-end=\"2227\" \/><p class=\"\" data-start=\"2229\" data-end=\"2418\">Para gestionar una devoluci\u00f3n, por favor, ponte en contacto con nuestro equipo de atenci\u00f3n al cliente a trav\u00e9s del correo electr\u00f3nico <strong data-start=\"2363\" data-end=\"2387\"><a class=\"cursor-pointer\" rel=\"noopener\" data-start=\"2365\" data-end=\"2385\">info@imprepapelx.com<\/a><\/strong> o llamando al <strong data-start=\"2402\" data-end=\"2417\">966 613 220<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>T\u00e9rminos y Condiciones T\u00e9rminos y condiciones de uso de Imprepapelx S.L.U. Estos t\u00e9rminos y condiciones rigen el uso del sitio web y la tienda online de Imprepapelx S.L.U. Al acceder o utilizar este sitio web, usted acepta estar sujeto a estos t\u00e9rminos y condiciones. 1. Aceptaci\u00f3n de los t\u00e9rminos Al utilizar este sitio web, usted [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":8,"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":357,"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/pages\/157\/revisions\/357"}],"wp:attachment":[{"href":"https:\/\/demo1.chequechulo.com\/fr\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}